{"id":1803,"date":"2023-08-28T19:36:38","date_gmt":"2023-08-28T22:36:38","guid":{"rendered":"https:\/\/joiadecoracoes.com.br\/?page_id=1803"},"modified":"2023-09-18T23:54:28","modified_gmt":"2023-09-19T02:54:28","slug":"cortina-para-cozinha","status":"publish","type":"page","link":"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-cozinha\/","title":{"rendered":"Cortina para Cozinha"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"1803\" class=\"elementor elementor-1803\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4e447e9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4e447e9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-a889156\" data-id=\"a889156\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a09e8d elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"8a09e8d\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;far fa-edit\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-regular&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/joiadecoracoes.com.br\/wp-content\/plugins\/pro-elements\/assets\/css\/widget-nav-menu.min.css\">\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open fas fa-list\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-8a09e8d\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-600\"><a href=\"https:\/\/joiadecoracoes.com.br\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-593\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-sala-3\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Sala<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-592\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-quarto-3\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Quarto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1845\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-cozinha\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Cozinha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-594\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-quarto\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Quarto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-591\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-area-externa\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana \u00c1rea Externa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-590\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-cozinha\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Cozinha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-589\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-escritorio\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Escrit\u00f3rio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1992\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/politica-privacidade\/\" class=\"elementor-item\" tabindex=\"-1\">Pol\u00edtica de Privacidade<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5052289 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5052289\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5507cd2\" data-id=\"5507cd2\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-157f562 elementor-widget elementor-widget-spacer\" data-id=\"157f562\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-27ec64c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"27ec64c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Cortina Para Cozinha<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-25c6a22 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"25c6a22\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-525a7aa elementor-arrows-position-outside elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"525a7aa\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide,.elementor-image-carousel-wrapper:not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-cozinha_rolo_2-300x300.jpg\" alt=\"joia-decoracoes-persiana-cozinha_rolo_2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-cozinha_rolo-300x300.jpg\" alt=\"joia-decoracoes-persiana-cozinha_rolo\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-cozinha_romana-300x300.jpg\" alt=\"joia-decoracoes-persiana-cozinha_romana\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-cozinha_rolo_3-300x300.jpg\" alt=\"joia-decoracoes-persiana-cozinha_rolo_3\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-cozinha_rolo_4-300x300.jpg\" alt=\"joia-decoracoes-persiana-cozinha_rolo_4\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8c0b8df elementor-widget elementor-widget-text-editor\" data-id=\"8c0b8df\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>A partir de R$ 74,56 o m\u00b2<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5077ad1 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"5077ad1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">OR\u00c7AMENTO<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b7f450d elementor-widget elementor-widget-text-editor\" data-id=\"b7f450d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>A cortina ideal para cozinha, na verdade \u00e9 uma persiana (risos).<\/p><p>A cozinha \u00e9 um local de f\u00e1cil ac\u00famulo de gordura e odores naturais aos alimentos que ali s\u00e3o preparados. Portanto \u00e9 natural que os objetos inseridos nesse ambiente retenham parte desse odor.\u00a0 \u00a0<\/p><p>Nesse sentido, a persiana \u00e9 a melhor op\u00e7\u00e3o para cozinha, pois sua manuten\u00e7\u00e3o e higiene s\u00e3o infinitamente mais simples comparados \u00e0 cortina.<\/p><p>Agora, comprar uma <strong>persiana para cozinha<\/strong>\u00a0exige conhecer as diferentes op\u00e7\u00f5es de material, modelo e estilos de persianas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be8926b elementor-widget elementor-widget-text-editor\" data-id=\"be8926b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Separamos algumas dicas para ajud\u00e1-lo a comprar a persiana certa para a sua cozinha e evitar arrependimentos. Se estiver sem tempo para ler, tire suas d\u00favidas diretamente por telefone.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-da055da elementor-widget elementor-widget-text-editor\" data-id=\"da055da\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-1\">Dica n\u00ba1 &#8211; Material<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6710fc0 elementor-widget elementor-widget-text-editor\" data-id=\"6710fc0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-2\">Dica n\u00ba2 &#8211; Modelo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a286b63 elementor-widget elementor-widget-text-editor\" data-id=\"a286b63\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-3\">Dica n\u00ba3 &#8211; Estilo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-89a0b49 elementor-widget elementor-widget-text-editor\" data-id=\"89a0b49\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-4\">Dica n\u00ba4 &#8211; Cor<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8bbcd14 elementor-widget elementor-widget-text-editor\" data-id=\"8bbcd14\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-5\">Dica n\u00ba5 &#8211; Medidas<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d61fd9a elementor-widget elementor-widget-text-editor\" data-id=\"d61fd9a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-6\">Dica n\u00ba6 &#8211; Acionamento<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e03f257 elementor-widget elementor-widget-text-editor\" data-id=\"e03f257\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-7\">Dica n\u00ba7 &#8211; Or\u00e7amento<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e19583a elementor-widget elementor-widget-text-editor\" data-id=\"e19583a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-8\">Dica n\u00ba8 &#8211; Instala\u00e7\u00e3o<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a63ff3 elementor-widget elementor-widget-text-editor\" data-id=\"9a63ff3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#resumo\">Resumo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2f4452a elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"2f4452a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">tire suas d\u00favidas por telefone<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b636f60 elementor-widget elementor-widget-heading\" data-id=\"b636f60\" data-element_type=\"widget\" id=\"dica-1\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba1 - Material<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e552aaf elementor-widget elementor-widget-text-editor\" data-id=\"e552aaf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o material de sua prefer\u00eancia. Os materiais mais comuns em <strong>persianas para cozinha<\/strong> s\u00e3o: tecido (mais vendido), alum\u00ednio e madeira.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06747ea elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06747ea\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7257532\" data-id=\"7257532\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a1ee61a elementor-invisible elementor-widget elementor-widget-image\" data-id=\"a1ee61a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo.png\" class=\"attachment-large size-large wp-image-161\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a43648e elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a43648e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TECIDO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a60fa74\" data-id=\"a60fa74\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2a53a25 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2a53a25\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio.png\" class=\"attachment-large size-large wp-image-162\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cf93b8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4cf93b8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALUM\u00cdNIO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-54239c6\" data-id=\"54239c6\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b00e715 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"b00e715\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes.png\" class=\"attachment-large size-large wp-image-163\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a7513e8 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a7513e8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MADEIRA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-51e0cc8 elementor-widget elementor-widget-heading\" data-id=\"51e0cc8\" data-element_type=\"widget\" id=\"dica-2\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba2 - Modelo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0c8e84 elementor-widget elementor-widget-text-editor\" data-id=\"d0c8e84\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o modelo de persiana ideal para voc\u00ea. As persianas mais comuns s\u00e3o:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef5248d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ef5248d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Rol\u00f4<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0bfca26 elementor-widget elementor-widget-image\" data-id=\"0bfca26\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-rolo-300x300.jpg\" class=\"attachment-medium size-medium wp-image-227\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-rolo-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-rolo-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-rolo.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a1c857 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"5a1c857\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Romana<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-377f613 elementor-widget elementor-widget-image\" data-id=\"377f613\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-300x300.jpg\" class=\"attachment-medium size-medium wp-image-233\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-612bdea elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"612bdea\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Painel<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-faa3835 elementor-widget elementor-widget-image\" data-id=\"faa3835\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-painel2-300x300.jpg\" class=\"attachment-medium size-medium wp-image-528\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-painel2-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-painel2-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-painel2.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f02cd2d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"f02cd2d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Double-Vision<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f8e26c elementor-widget elementor-widget-image\" data-id=\"6f8e26c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-double_vision-300x300.jpg\" class=\"attachment-medium size-medium wp-image-243\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-double_vision-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-double_vision-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-double_vision.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-96e47a1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"96e47a1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Vertical<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85a40ef elementor-widget elementor-widget-image\" data-id=\"85a40ef\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-300x300.jpg\" class=\"attachment-medium size-medium wp-image-529\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb56c95 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"bb56c95\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Horizontal<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5003e4d elementor-widget elementor-widget-image\" data-id=\"5003e4d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-300x300.jpg\" class=\"attachment-medium size-medium wp-image-235\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df84606 elementor-widget elementor-widget-text-editor\" data-id=\"df84606\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ao escolher uma persiana para sua cozinha, voc\u00ea deve considerar que o local ir\u00e1 acumular gordura, portanto \u00e9 importante ter em mente que voc\u00ea precisar\u00e1 higienizar sua persiana regularmente (1 ou 2x por ano).<\/p>\n<p>E claro, dependendo do modelo, essa tarefa ser\u00e1 mais simples ou mais complexa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dbe1b2 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1dbe1b2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">quero saber mais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b2b06ce elementor-widget elementor-widget-heading\" data-id=\"b2b06ce\" data-element_type=\"widget\" id=\"dica-3\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba3 - Estilo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e456989 elementor-widget elementor-widget-text-editor\" data-id=\"e456989\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o estilo da sua persiana. Os estilos mais comuns para persianas s\u00e3o:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ddf04d1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ddf04d1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Screen<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3d4b33 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"a3d4b33\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f703f91 elementor-widget elementor-widget-image\" data-id=\"f703f91\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-263\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">teste de luz - sem tecido<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cbefc13 elementor-widget elementor-widget-image\" data-id=\"cbefc13\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-5-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-268\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-5-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-5-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-5-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 5%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a3c29d3 elementor-widget elementor-widget-image\" data-id=\"a3c29d3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-3-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-269\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-3-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-3-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-3-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 3%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-65fdae1 elementor-widget elementor-widget-image\" data-id=\"65fdae1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-1-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-270\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-1-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-1-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-screen-1-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 1%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eac1505 elementor-widget elementor-widget-text-editor\" data-id=\"eac1505\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido Screen ainda pode se diferenciar pelo seu fator de abertura (1%, 3% ou 5%). Quanto maior o fator de abertura do tecido, maior a entrada de luz, ent\u00e3o se voc\u00ea deseja deixar o local mais\u00a0 escuro, a solu\u00e7\u00e3o ideal para voc\u00ea seria o tecido Screen 1% ou o Tecido Blackout, que falaremos a seguir.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8051ec1 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"8051ec1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Blackout<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1350eaf elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1350eaf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bfdf7e5 elementor-widget elementor-widget-image\" data-id=\"bfdf7e5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-blackout-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-272\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-blackout-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-blackout-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-blackout-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Blackout<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b73cf6 elementor-widget elementor-widget-text-editor\" data-id=\"1b73cf6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido Blackout \u00e9 um tecido opaco que bloqueia totalmente a entrada de luz, proporcionando maior privacidade.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72a33fa elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"72a33fa\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Transl\u00facido<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-debb3f6 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"debb3f6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c66a68d elementor-widget elementor-widget-image\" data-id=\"c66a68d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-translucido-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-277\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-translucido-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-translucido-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-translucido-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Transl\u00facido<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bea8eb4 elementor-widget elementor-widget-text-editor\" data-id=\"bea8eb4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido transl\u00facido mant\u00e9m o ambiente claro, pois seu tecido permite a entrada de luz de forma difusa, reduzindo parcialmente a vis\u00e3o exterior.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba0a598 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ba0a598\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Alum\u00ednio<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6ee9c0d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"6ee9c0d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para o modelo Horizontal)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-343e13c elementor-widget elementor-widget-image\" data-id=\"343e13c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-300x300.jpg\" class=\"attachment-medium size-medium wp-image-244\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68f9f06 elementor-widget elementor-widget-text-editor\" data-id=\"68f9f06\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Onde tudo come\u00e7ou \u2013 persianas mais objetivas que controlam facilmente a luminosidade, alterando a disposi\u00e7\u00e3o de suas l\u00e2minas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45cb2a3 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"45cb2a3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Madeira<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d7c6b7f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d7c6b7f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para o modelo Horizontal)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-68b463f elementor-widget elementor-widget-image\" data-id=\"68b463f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-300x300.jpg\" class=\"attachment-medium size-medium wp-image-245\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3aa6230 elementor-widget elementor-widget-text-editor\" data-id=\"3aa6230\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ideal para voc\u00ea que quer deixar seu local com um aspecto mais r\u00fastico ou buc\u00f3lico.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6203cc6 elementor-widget elementor-widget-heading\" data-id=\"6203cc6\" data-element_type=\"widget\" id=\"dica-4\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba4- Cor<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aba27fe elementor-widget elementor-widget-text-editor\" data-id=\"aba27fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha a cor da persiana: A cor da persiana \u00e9 uma escolha importante, pois pode afetar o visual da sua cozinha. Escolha uma cor que complemente a decora\u00e7\u00e3o existente ou uma cor neutra que se adapte facilmente a mudan\u00e7as na decora\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a374ded elementor-widget elementor-widget-text-editor\" data-id=\"a374ded\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para facilitar sua decis\u00e3o, agende uma visita t\u00e9cnica conosco e nossos consultores ir\u00e3o te apresentar todas as cores dispon\u00edveis para o modelo que voc\u00ea mais gostou \u2013 o melhor de tudo \u00e9 que voc\u00ea nem precisa sair da sua casa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eff557c elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"eff557c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131026b elementor-widget elementor-widget-text-editor\" data-id=\"131026b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Atendimento em toda Regi\u00e3o Metropolitana de S\u00e3o Paulo e Litoral Paulista (S\u00e3o Paulo, Barueri, Cotia, Jundia\u00ed, Mau\u00e1, Santana do Parna\u00edba, Santos, S\u00e3o Bernardo, S\u00e3o Caetano, &#8230;)\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-40afb17 elementor-widget elementor-widget-heading\" data-id=\"40afb17\" data-element_type=\"widget\" id=\"dica-5\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba5- Medidas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-986c7d9 elementor-widget elementor-widget-text-editor\" data-id=\"986c7d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Me\u00e7a a janela da sua cozinha. Certifique-se de medir a largura e a altura da janela para ter certeza de que a persiana que voc\u00ea escolheu se encaixar\u00e1 perfeitamente. A altura deve ser medida em pelo menos 3 pontos, para que voc\u00ea possa avaliar se existe desn\u00edvel no seu piso ou no balc\u00e3o onde est\u00e1 a janela da sua cozinha.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bad8b8c elementor-widget elementor-widget-text-editor\" data-id=\"bad8b8c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Mais f\u00e1cil: agende uma visita t\u00e9cnica e nossos consultores al\u00e9m de levar nosso mostru\u00e1rio, para que voc\u00ea possa escolher a cor, tamb\u00e9m realizar\u00e3o as medi\u00e7\u00f5es corretamente. Assim voc\u00ea evita problemas na instala\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad75511 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"ad75511\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7c765cd elementor-widget elementor-widget-heading\" data-id=\"7c765cd\" data-element_type=\"widget\" id=\"dica-6\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba6- Utiliza\u00e7\u00e3o<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-80ec80a elementor-widget elementor-widget-text-editor\" data-id=\"80ec80a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Acionamento: como voc\u00ea deseja utilizar sua persiana? Voc\u00ea prefere o controle manual ou prefere as persianas automatizadas que te permitem acionar por voz ou celular os comandos de abrir e fechar, por exemplo? A maioria das persianas hoje j\u00e1 oferecem a op\u00e7\u00e3o por acionamento manual ou automatizado.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-58002f4 elementor-widget elementor-widget-heading\" data-id=\"58002f4\" data-element_type=\"widget\" id=\"dica-7\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba7- Or\u00e7amento<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eae04c6 elementor-widget elementor-widget-text-editor\" data-id=\"eae04c6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Depois de anotar as medidas e ter de escolhido o material, o modelo, o estilo, a cor da persiana e a forma de acionamento, \u00e9 hora de solicitar seu or\u00e7amento.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e91368b elementor-widget elementor-widget-heading\" data-id=\"e91368b\" data-element_type=\"widget\" id=\"dica-8\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba8- Instala\u00e7\u00e3o<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ada513 elementor-widget elementor-widget-text-editor\" data-id=\"9ada513\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Chegou a hora da instala\u00e7\u00e3o. Se voc\u00ea \u00e9 do tipo de pessoa que gosta de p\u00f4r a \u201cm\u00e3o na massa\u201d com todas as tarefas do lar, siga as instru\u00e7\u00f5es do fabricante e instale sua persiana.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca787d7 elementor-widget elementor-widget-text-editor\" data-id=\"ca787d7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Se voc\u00ea quiser ganhar tempo, ou n\u00e3o tiver tanto interesse por essa atividade, deixe conosco a etapa de instala\u00e7\u00e3o da sua persiana. Voc\u00ea se surpreender\u00e1 com a organiza\u00e7\u00e3o do nosso time na instala\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-480c0a3 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"480c0a3\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar Instala\u00e7\u00e3o<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c3209e8 elementor-widget elementor-widget-heading\" data-id=\"c3209e8\" data-element_type=\"widget\" id=\"resumo\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Resumo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3eaf616 elementor-widget elementor-widget-text-editor\" data-id=\"3eaf616\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ao comprar uma persiana para sua cozinha voc\u00ea deve escolher entre 3 materiais (tecido, alum\u00ednio ou madeira), depois sobre 6 modelos principais (rol\u00f4, romana, painel, double vision, vertical e horizontal) e na sequ\u00eancia pelo estilo (Screen 1%, Screen 3%, Screen 5%, Blackout, Transl\u00facido, Alum\u00ednio ou Madeira) e por fim se deseja acionamento manual ou automatizado para sua persiana.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-081cfde elementor-widget elementor-widget-text-editor\" data-id=\"081cfde\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Comprar uma <strong>persiana para cozinha<\/strong>\u00a0n\u00e3o \u00e9 tarefa f\u00e1cil. Se quiser ajuda, agende uma visita t\u00e9cnica com a gente, n\u00f3s apresentaremos nosso mostru\u00e1rio, lhe daremos sugest\u00f5es e faremos as medi\u00e7\u00f5es do seu ambiente.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2302a22 elementor-widget elementor-widget-text-editor\" data-id=\"2302a22\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Seguindo essas etapas, voc\u00ea pode escolher e comprar a persiana certa para a sua cozinha e desfrutar de um ambiente mais confort\u00e1vel e acolhedor.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-436d96d elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"436d96d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4b70f85 elementor-widget elementor-widget-text-editor\" data-id=\"4b70f85\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Atendimento em toda Regi\u00e3o Metropolitana de S\u00e3o Paulo e Litoral Paulista (S\u00e3o Paulo, Barueri, Cotia, Jundia\u00ed, Mau\u00e1, Santana do Parna\u00edba, Santos, S\u00e3o Bernardo, S\u00e3o Caetano, &#8230;)\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-29ab31f elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"29ab31f\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-992c6e5\" data-id=\"992c6e5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38989d1 elementor-widget elementor-widget-heading\" data-id=\"38989d1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como Trabalhamos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57c77be elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"57c77be\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/joiadecoracoes.com.br\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1- COMENTE SUA IDEIA ENTRANDO EM CONTATO PELO WHATSAPP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2- RECEBA UM OR\u00c7AMENTO PR\u00c9VIO<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3- AGENDE UMA VISITA T\u00c9CNICA PARA DISCUSS\u00c3O DE MODELOS E MEDI\u00c7\u00c3O OFICIAL<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4- RECEBA SEU OR\u00c7AMENTO FINAL<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5- AGENDE A INSTALA\u00c7\u00c3O E DEPOIS \u00c9 S\u00d3 CURTIR SEU NOVO AMBIENTE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7183205 elementor-widget elementor-widget-spacer\" data-id=\"7183205\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1049f6f elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1049f6f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">comente sua ideia<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77beb02 elementor-widget elementor-widget-spacer\" data-id=\"77beb02\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8ff0492 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8ff0492\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cac32e\" data-id=\"8cac32e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3ce3dc elementor-widget elementor-widget-image\" data-id=\"e3ce3dc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-768x461.png\" class=\"attachment-medium_large size-medium_large wp-image-85\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-768x461.png 768w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-300x180.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-1024x614.png 1024w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-1536x922.png 1536w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-2048x1229.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df611c1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"df611c1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-99f69ee\" data-id=\"99f69ee\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fec8697 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"fec8697\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REDES SOCIAIS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d4c76d6 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"d4c76d6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0814944 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"0814944\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>ACOMPANHE NOSSO TRABALHO NO INSTAGRAM<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21b13bf elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"21b13bf\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.instagram.com\/joia_decoracoes\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\" id=\"btn_instagram\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">INSTAGRAM<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Cortina Para Cozinha Anterior Pr\u00f3ximo A partir de R$ 74,56 o m\u00b2 OR\u00c7AMENTO A cortina ideal para cozinha, na verdade \u00e9 uma persiana (risos). A cozinha \u00e9 um local de f\u00e1cil ac\u00famulo de gordura e odores naturais aos alimentos que ali s\u00e3o preparados. Portanto \u00e9 natural que os objetos inseridos nesse ambiente retenham parte desse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[]},"_links":{"self":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803"}],"collection":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=1803"}],"version-history":[{"count":13,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803\/revisions"}],"predecessor-version":[{"id":1851,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/1803\/revisions\/1851"}],"wp:attachment":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=1803"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}