{"id":578,"date":"2023-05-29T17:28:21","date_gmt":"2023-05-29T20:28:21","guid":{"rendered":"https:\/\/joiadecoracoes.com.br\/?page_id=578"},"modified":"2023-10-05T15:21:02","modified_gmt":"2023-10-05T18:21:02","slug":"persiana-para-escritorio","status":"publish","type":"page","link":"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-escritorio\/","title":{"rendered":"Persiana para Escrit\u00f3rio"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"578\" class=\"elementor elementor-578\">\n\t\t\t\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a6f2256 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a6f2256\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;animation&quot;:&quot;none&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0061c3f\" data-id=\"0061c3f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a27bd60 elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"a27bd60\" data-element_type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;dropdown&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;far fa-edit\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;fa-regular&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/joiadecoracoes.com.br\/wp-content\/plugins\/pro-elements\/assets\/css\/widget-nav-menu.min.css\">\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open fas fa-list\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t\t<span class=\"elementor-screen-only\">Menu<\/span>\n\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-a27bd60\" class=\"elementor-nav-menu\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-home menu-item-600\"><a href=\"https:\/\/joiadecoracoes.com.br\/\" class=\"elementor-item\" tabindex=\"-1\">Home<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-593\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-sala-3\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Sala<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-592\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-quarto-3\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Quarto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1845\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/cortina-para-cozinha\/\" class=\"elementor-item\" tabindex=\"-1\">Cortina para Cozinha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-594\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-quarto\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Quarto<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-591\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-area-externa\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana \u00c1rea Externa<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-590\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-cozinha\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Cozinha<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-589\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/persiana-para-escritorio\/\" class=\"elementor-item\" tabindex=\"-1\">Persiana para Escrit\u00f3rio<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-1992\"><a href=\"https:\/\/joiadecoracoes.com.br\/index.php\/politica-privacidade\/\" class=\"elementor-item\" tabindex=\"-1\">Pol\u00edtica de Privacidade<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f0ffaad elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f0ffaad\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c1e4a11\" data-id=\"c1e4a11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0e8ecc7 elementor-widget elementor-widget-spacer\" data-id=\"0e8ecc7\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-column .elementor-spacer-inner{height:var(--spacer-size)}.e-con{--container-widget-width:100%}.e-con-inner>.elementor-widget-spacer,.e-con>.elementor-widget-spacer{width:var(--container-widget-width,var(--spacer-size));--align-self:var(--container-widget-align-self,initial);--flex-shrink:0}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container,.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer,.e-con>.elementor-widget-spacer>.elementor-widget-container,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer{height:100%}.e-con-inner>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner,.e-con>.elementor-widget-spacer>.elementor-widget-container>.elementor-spacer>.elementor-spacer-inner{height:var(--container-widget-height,var(--spacer-size))}<\/style>\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-354335f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"354335f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h1 class=\"elementor-heading-title elementor-size-default\">Persiana Para Escrit\u00f3rio<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5e87bac elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"5e87bac\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-divider{--divider-border-style:none;--divider-border-width:1px;--divider-color:#2c2c2c;--divider-icon-size:20px;--divider-element-spacing:10px;--divider-pattern-height:24px;--divider-pattern-size:20px;--divider-pattern-url:none;--divider-pattern-repeat:repeat-x}.elementor-widget-divider .elementor-divider{display:flex}.elementor-widget-divider .elementor-divider__text{font-size:15px;line-height:1;max-width:95%}.elementor-widget-divider .elementor-divider__element{margin:0 var(--divider-element-spacing);flex-shrink:0}.elementor-widget-divider .elementor-icon{font-size:var(--divider-icon-size)}.elementor-widget-divider .elementor-divider-separator{display:flex;margin:0;direction:ltr}.elementor-widget-divider--view-line_icon .elementor-divider-separator,.elementor-widget-divider--view-line_text .elementor-divider-separator{align-items:center}.elementor-widget-divider--view-line_icon .elementor-divider-separator:after,.elementor-widget-divider--view-line_icon .elementor-divider-separator:before,.elementor-widget-divider--view-line_text .elementor-divider-separator:after,.elementor-widget-divider--view-line_text .elementor-divider-separator:before{display:block;content:\"\";border-bottom:0;flex-grow:1;border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--element-align-left .elementor-divider .elementor-divider-separator>.elementor-divider__svg:first-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-left .elementor-divider-separator:before{content:none}.elementor-widget-divider--element-align-left .elementor-divider__element{margin-left:0}.elementor-widget-divider--element-align-right .elementor-divider .elementor-divider-separator>.elementor-divider__svg:last-of-type{flex-grow:0;flex-shrink:100}.elementor-widget-divider--element-align-right .elementor-divider-separator:after{content:none}.elementor-widget-divider--element-align-right .elementor-divider__element{margin-right:0}.elementor-widget-divider:not(.elementor-widget-divider--view-line_text):not(.elementor-widget-divider--view-line_icon) .elementor-divider-separator{border-top:var(--divider-border-width) var(--divider-border-style) var(--divider-color)}.elementor-widget-divider--separator-type-pattern{--divider-border-style:none}.elementor-widget-divider--separator-type-pattern.elementor-widget-divider--view-line .elementor-divider-separator,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:after,.elementor-widget-divider--separator-type-pattern:not(.elementor-widget-divider--view-line) .elementor-divider-separator:before,.elementor-widget-divider--separator-type-pattern:not([class*=elementor-widget-divider--view]) .elementor-divider-separator{width:100%;min-height:var(--divider-pattern-height);-webkit-mask-size:var(--divider-pattern-size) 100%;mask-size:var(--divider-pattern-size) 100%;-webkit-mask-repeat:var(--divider-pattern-repeat);mask-repeat:var(--divider-pattern-repeat);background-color:var(--divider-color);-webkit-mask-image:var(--divider-pattern-url);mask-image:var(--divider-pattern-url)}.elementor-widget-divider--no-spacing{--divider-pattern-size:auto}.elementor-widget-divider--bg-round{--divider-pattern-repeat:round}.rtl .elementor-widget-divider .elementor-divider__text{direction:rtl}.e-con-inner>.elementor-widget-divider,.e-con>.elementor-widget-divider{width:var(--container-widget-width,100%);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2d5528 elementor-arrows-position-outside elementor-pagination-position-outside elementor-invisible elementor-widget elementor-widget-image-carousel\" data-id=\"c2d5528\" data-element_type=\"widget\" data-settings=\"{&quot;slides_to_show&quot;:&quot;1&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;,&quot;autoplay_speed&quot;:3000,&quot;navigation&quot;:&quot;both&quot;,&quot;autoplay&quot;:&quot;yes&quot;,&quot;pause_on_hover&quot;:&quot;yes&quot;,&quot;pause_on_interaction&quot;:&quot;yes&quot;,&quot;infinite&quot;:&quot;yes&quot;,&quot;effect&quot;:&quot;slide&quot;,&quot;speed&quot;:500}\" data-widget_type=\"image-carousel.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image-carousel .swiper,.elementor-widget-image-carousel .swiper-container{position:static}.elementor-widget-image-carousel .swiper-container .swiper-slide figure,.elementor-widget-image-carousel .swiper .swiper-slide figure{line-height:inherit}.elementor-widget-image-carousel .swiper-slide{text-align:center}.elementor-image-carousel-wrapper:not(.swiper-container-initialized) .swiper-slide,.elementor-image-carousel-wrapper:not(.swiper-initialized) .swiper-slide{max-width:calc(100% \/ var(--e-image-carousel-slides-to-show, 3))}<\/style>\t\t<div class=\"elementor-image-carousel-wrapper swiper\" dir=\"ltr\">\n\t\t\t<div class=\"elementor-image-carousel swiper-wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-escritorio-horizontal_2-300x300.jpg\" alt=\"joia-decoracoes-persiana-escritorio-horizontal_2\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-escritorio-horizontal-300x300.jpg\" alt=\"joia-decoracoes-persiana-escritorio-horizontal\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-escritorio-rolo-300x300.jpg\" alt=\"joia-decoracoes-persiana-escritorio-rolo\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-escritorio-rolo_branco-300x300.jpg\" alt=\"joia-decoracoes-persiana-escritorio-rolo_branco\" \/><\/figure><\/div><div class=\"swiper-slide\"><figure class=\"swiper-slide-inner\"><img decoding=\"async\" class=\"swiper-slide-image\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/08\/joia-decoracoes-persiana-escritorio-rolo_preto-300x300.jpg\" alt=\"joia-decoracoes-persiana-escritorio-rolo_preto\" \/><\/figure><\/div>\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-prev\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-left\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Anterior<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div class=\"elementor-swiper-button elementor-swiper-button-next\">\n\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"eicon-chevron-right\"><\/i>\t\t\t\t\t\t<span class=\"elementor-screen-only\">Pr\u00f3ximo<\/span>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c384759 elementor-widget elementor-widget-text-editor\" data-id=\"c384759\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#818a91;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#818a91;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>A partir de R$ 149,97 o m\u00b2<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a5b9b1 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"5a5b9b1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">OR\u00c7AMENTO<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-00dbded elementor-widget elementor-widget-text-editor\" data-id=\"00dbded\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>E se voc\u00ea comprar uma persiana que n\u00e3o combina com seu escrit\u00f3rio? E se ela n\u00e3o bloquear a luz como voc\u00ea gostaria?<\/p><p>Comprar uma <strong>persiana para escrit\u00f3rio<\/strong>\u00a0exige conhecer as diferentes op\u00e7\u00f5es de material, modelo e estilos de persianas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26e5c6f elementor-widget elementor-widget-text-editor\" data-id=\"26e5c6f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Separamos algumas dicas para ajud\u00e1-lo a comprar a persiana certa para o seu escrit\u00f3rio e evitar arrependimentos, afinal de contas \u00e9 dif\u00edcil ter que trabalhar olhando para os seus pr\u00f3prios erros (risos). Se estiver sem tempo para ler, tire suas d\u00favidas diretamente por telefone.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-09f8c11 elementor-widget elementor-widget-text-editor\" data-id=\"09f8c11\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-1\">Dica n\u00ba1 &#8211; Material<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a404b1 elementor-widget elementor-widget-text-editor\" data-id=\"8a404b1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-2\">Dica n\u00ba2 &#8211; Modelo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33678d9 elementor-widget elementor-widget-text-editor\" data-id=\"33678d9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-3\">Dica n\u00ba3 &#8211; Estilo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-33cc07c elementor-widget elementor-widget-text-editor\" data-id=\"33cc07c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-4\">Dica n\u00ba4 &#8211; Cor<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fec8bc elementor-widget elementor-widget-text-editor\" data-id=\"6fec8bc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-5\">Dica n\u00ba5 &#8211; Medidas<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca3119a elementor-widget elementor-widget-text-editor\" data-id=\"ca3119a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-6\">Dica n\u00ba6 &#8211; Acionamento<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-771187e elementor-widget elementor-widget-text-editor\" data-id=\"771187e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-7\">Dica n\u00ba7 &#8211; Or\u00e7amento<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-888ed62 elementor-widget elementor-widget-text-editor\" data-id=\"888ed62\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#dica-8\">Dica n\u00ba8 &#8211; Instala\u00e7\u00e3o<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1bc53ab elementor-widget elementor-widget-text-editor\" data-id=\"1bc53ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><a href=\"#resumo\">Resumo<\/a><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ad58f35 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"ad58f35\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">tire suas d\u00favidas por telefone<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0091964 elementor-widget elementor-widget-heading\" data-id=\"0091964\" data-element_type=\"widget\" id=\"dica-1\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba1 - Material<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b37807 elementor-widget elementor-widget-text-editor\" data-id=\"1b37807\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o material de sua prefer\u00eancia. Os materiais mais comuns em <strong>persianas para escrit\u00f3rio<\/strong> s\u00e3o: tecido (mais vendido), alum\u00ednio e madeira.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ee178de elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ee178de\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-070b5de\" data-id=\"070b5de\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-080d53c elementor-invisible elementor-widget elementor-widget-image\" data-id=\"080d53c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.11.5 - 14-03-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo.png\" class=\"attachment-large size-large wp-image-161\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-cortina-rolo-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c09fd79 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"c09fd79\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">TECIDO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-96d77ab\" data-id=\"96d77ab\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f529654 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"f529654\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio.png\" class=\"attachment-large size-large wp-image-162\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-aluminio-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d70eb56 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d70eb56\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">ALUM\u00cdNIO<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-cabeadd\" data-id=\"cabeadd\" data-element_type=\"column\" data-settings=\"{&quot;animation_mobile&quot;:&quot;fadeInUp&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6396e0f elementor-invisible elementor-widget elementor-widget-image\" data-id=\"6396e0f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"512\" height=\"512\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes.png\" class=\"attachment-large size-large wp-image-163\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes.png 512w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/icone-persiana-de-madeira-joia-decoracoes-150x150.png 150w\" sizes=\"(max-width: 512px) 100vw, 512px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fe8b7a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"7fe8b7a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">MADEIRA<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac790b6 elementor-widget elementor-widget-heading\" data-id=\"ac790b6\" data-element_type=\"widget\" id=\"dica-2\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba2 - Modelo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f33696d elementor-widget elementor-widget-text-editor\" data-id=\"f33696d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o modelo de persiana ideal para voc\u00ea. As persianas mais comuns s\u00e3o:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec9aa65 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"ec9aa65\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Rol\u00f4<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-048c723 elementor-widget elementor-widget-image\" data-id=\"048c723\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-rolo-home-office-2-300x300.png\" class=\"attachment-medium size-medium wp-image-1907\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-rolo-home-office-2-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-rolo-home-office-2-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-rolo-home-office-2.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a53e94 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"4a53e94\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Romana<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-10ae86b elementor-widget elementor-widget-image\" data-id=\"10ae86b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-300x300.jpg\" class=\"attachment-medium size-medium wp-image-233\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-romana.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e50bc17 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"e50bc17\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Painel<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb66767 elementor-widget elementor-widget-image\" data-id=\"cb66767\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-escritorio-rolo_branco-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1910\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-escritorio-rolo_branco-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-escritorio-rolo_branco-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-escritorio-rolo_branco.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d2e867f elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"d2e867f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Double-Vision<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6fab00e elementor-widget elementor-widget-image\" data-id=\"6fab00e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-quarto-double-vision-300x300.jpg\" class=\"attachment-medium size-medium wp-image-1903\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-quarto-double-vision-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-quarto-double-vision-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-quarto-double-vision.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b0e5281 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b0e5281\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Vertical<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-74ed715 elementor-widget elementor-widget-image\" data-id=\"74ed715\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-300x300.jpg\" class=\"attachment-medium size-medium wp-image-529\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-vertical.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-11eda7a elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"11eda7a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Horizontal<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59a0e47 elementor-widget elementor-widget-image\" data-id=\"59a0e47\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-300x300.jpg\" class=\"attachment-medium size-medium wp-image-235\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-horizontal.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cb7edf0 elementor-widget elementor-widget-text-editor\" data-id=\"cb7edf0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Considere o estilo do seu escrit\u00f3rio e escolha a persiana que melhor se adapta \u00e0s suas necessidades e gostos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9e9b950 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"9e9b950\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">quero saber mais<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93d180d elementor-widget elementor-widget-heading\" data-id=\"93d180d\" data-element_type=\"widget\" id=\"dica-3\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba3 - Estilo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf35fda elementor-widget elementor-widget-text-editor\" data-id=\"cf35fda\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha o estilo da sua persiana. Os estilos mais comuns para persianas s\u00e3o:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c70248 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1c70248\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Screen<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3d5461d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3d5461d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a75bcf0 elementor-widget elementor-widget-image\" data-id=\"a75bcf0\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-300x300.jpg\" class=\"attachment-medium size-medium wp-image-263\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-teste-luz-p.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">teste de luz - sem tecido<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8605ae3 elementor-widget elementor-widget-image\" data-id=\"8605ae3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-5-300x300.png\" class=\"attachment-medium size-medium wp-image-1893\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-5-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-5-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-5.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 5%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d0877de elementor-widget elementor-widget-image\" data-id=\"d0877de\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-3-300x300.png\" class=\"attachment-medium size-medium wp-image-1894\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-3-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-3-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-3.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 3%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cf22bd3 elementor-widget elementor-widget-image\" data-id=\"cf22bd3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-1-300x300.png\" class=\"attachment-medium size-medium wp-image-1895\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-1-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-1-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-screen-1.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Screen 1%<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8de65d2 elementor-widget elementor-widget-text-editor\" data-id=\"8de65d2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido Screen ainda pode se diferenciar pelo seu fator de abertura (1%, 3% ou 5%). Quanto maior o fator de abertura do tecido, maior a entrada de luz, ent\u00e3o se voc\u00ea deseja deixar o local mais escuro, a solu\u00e7\u00e3o ideal para voc\u00ea seria o tecido Screen 1% ou o Tecido Blackout, que falaremos a seguir.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-244108c elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"244108c\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Blackout<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1833f76 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"1833f76\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4cd644e elementor-widget elementor-widget-image\" data-id=\"4cd644e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-blackout-300x300.png\" class=\"attachment-medium size-medium wp-image-1896\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-blackout-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-blackout-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-blackout.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Blackout<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08147ab elementor-widget elementor-widget-text-editor\" data-id=\"08147ab\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido Blackout \u00e9 um tecido opaco que bloqueia totalmente a entrada de luz, proporcionando maior privacidade.\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-938b9ba elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"938b9ba\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Transl\u00facido<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b07ac45 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"b07ac45\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para os modelos rol\u00f4, romana, painel, double vision e  vertical)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-532cf2e elementor-widget elementor-widget-image\" data-id=\"532cf2e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t<figure class=\"wp-caption\">\n\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-translucido-300x300.png\" class=\"attachment-medium size-medium wp-image-1897\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-translucido-300x300.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-translucido-150x150.png 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/10\/joia-decoracoes-persiana-bloqueio-luz-translucido.png 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t<figcaption class=\"widget-image-caption wp-caption-text\">Transl\u00facido<\/figcaption>\n\t\t\t\t\t\t\t\t\t\t<\/figure>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49498f5 elementor-widget elementor-widget-text-editor\" data-id=\"49498f5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>O tecido transl\u00facido mant\u00e9m o ambiente claro, pois seu tecido permite a entrada de luz de forma difusa, reduzindo parcialmente a vis\u00e3o exterior.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af8b972 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"af8b972\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Alum\u00ednio<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3db1500 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"3db1500\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para o modelo Horizontal)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c85920b elementor-widget elementor-widget-image\" data-id=\"c85920b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-300x300.jpg\" class=\"attachment-medium size-medium wp-image-244\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-aluminio.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6a768b3 elementor-widget elementor-widget-text-editor\" data-id=\"6a768b3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Onde tudo come\u00e7ou \u2013 persianas mais objetivas que controlam facilmente a luminosidade, alterando a disposi\u00e7\u00e3o de suas l\u00e2minas.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-643fe58 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"643fe58\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h3 class=\"elementor-heading-title elementor-size-small\">Madeira<\/h3>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-60a268d elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"60a268d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h4 class=\"elementor-heading-title elementor-size-small\">(dispon\u00edvel para o modelo Horizontal)<\/h4>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c50d9d8 elementor-widget elementor-widget-image\" data-id=\"c50d9d8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-300x300.jpg\" class=\"attachment-medium size-medium wp-image-245\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-300x300.jpg 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira-150x150.jpg 150w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/05\/joia-decoracoes-persiana-quarto-madeira.jpg 512w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46d9e9c elementor-widget elementor-widget-text-editor\" data-id=\"46d9e9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ideal para voc\u00ea que quer deixar seu home-office mais aconchegante.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71d0fbe elementor-widget elementor-widget-heading\" data-id=\"71d0fbe\" data-element_type=\"widget\" id=\"dica-4\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba4- Cor<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-048ef86 elementor-widget elementor-widget-text-editor\" data-id=\"048ef86\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Escolha a cor da persiana: A cor da persiana \u00e9 uma escolha importante, pois pode afetar o visual do seu escrit\u00f3rio. Escolha uma cor que complemente a decora\u00e7\u00e3o existente no escrit\u00f3rio ou uma cor neutra que se adapte facilmente a mudan\u00e7as na decora\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-012152e elementor-widget elementor-widget-text-editor\" data-id=\"012152e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para facilitar sua decis\u00e3o, agende uma visita t\u00e9cnica conosco e nossos consultores ir\u00e3o te apresentar todas as cores dispon\u00edveis para o modelo que voc\u00ea mais gostou \u2013 o melhor de tudo \u00e9 que voc\u00ea nem precisa sair da sua casa.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06d18e0 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"06d18e0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7914697 elementor-widget elementor-widget-text-editor\" data-id=\"7914697\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Atendimento em toda Regi\u00e3o Metropolitana de S\u00e3o Paulo e Litoral Paulista (S\u00e3o Paulo, Barueri, Cotia, Jundia\u00ed, Mau\u00e1, Santana do Parna\u00edba, Santos, S\u00e3o Bernardo, S\u00e3o Caetano, &#8230;)\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5af6a6b elementor-widget elementor-widget-heading\" data-id=\"5af6a6b\" data-element_type=\"widget\" id=\"dica-5\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba5- Medidas<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ab0be3e elementor-widget elementor-widget-text-editor\" data-id=\"ab0be3e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Me\u00e7a a janela do seu escrit\u00f3rio. Certifique-se de medir a largura e a altura da janela para ter certeza de que a persiana que voc\u00ea escolheu se encaixar\u00e1 perfeitamente. A altura deve ser medida em pelo menos 3 pontos, para que voc\u00ea possa avaliar se existe desn\u00edvel no seu piso.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-731d3d0 elementor-widget elementor-widget-text-editor\" data-id=\"731d3d0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Mais f\u00e1cil: agende uma visita t\u00e9cnica e nossos consultores al\u00e9m de levar nosso mostru\u00e1rio, para que voc\u00ea possa escolher a cor, tamb\u00e9m realizar\u00e3o as medi\u00e7\u00f5es corretamente. Assim voc\u00ea evita problemas na instala\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1f994f8 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1f994f8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebe9230 elementor-widget elementor-widget-heading\" data-id=\"ebe9230\" data-element_type=\"widget\" id=\"dica-6\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba6- Utiliza\u00e7\u00e3o<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-baec889 elementor-widget elementor-widget-text-editor\" data-id=\"baec889\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Acionamento: como voc\u00ea deseja utilizar sua persiana? Voc\u00ea prefere o controle manual ou prefere as persianas automatizadas que te permitem acionar por voz ou celular os comandos de abrir e fechar, por exemplo? A maioria das persianas hoje j\u00e1 oferecem a op\u00e7\u00e3o por acionamento manual ou automatizado.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5bd5641 elementor-widget elementor-widget-heading\" data-id=\"5bd5641\" data-element_type=\"widget\" id=\"dica-7\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba7- Or\u00e7amento<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f5dc91 elementor-widget elementor-widget-text-editor\" data-id=\"6f5dc91\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Depois de anotar as medidas e ter de escolhido o material, o modelo, o estilo, a cor da persiana e a forma de acionamento, \u00e9 hora de solicitar seu or\u00e7amento.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c8a8a9f elementor-widget elementor-widget-heading\" data-id=\"c8a8a9f\" data-element_type=\"widget\" id=\"dica-8\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Dica n\u00ba8- Instala\u00e7\u00e3o<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f16ea6a elementor-widget elementor-widget-text-editor\" data-id=\"f16ea6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Chegou a hora da instala\u00e7\u00e3o. Se voc\u00ea \u00e9 do tipo de pessoa que gosta de p\u00f4r a \u201cm\u00e3o na massa\u201d com todas as tarefas do lar, siga as instru\u00e7\u00f5es do fabricante e instale sua persiana.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-457c6ef elementor-widget elementor-widget-text-editor\" data-id=\"457c6ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Se voc\u00ea quiser ganhar tempo, ou n\u00e3o tiver tanto interesse por essa atividade, deixe conosco a etapa de instala\u00e7\u00e3o da sua persiana. Voc\u00ea se surpreender\u00e1 com a organiza\u00e7\u00e3o do nosso time na instala\u00e7\u00e3o.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e3c647 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"8e3c647\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar Instala\u00e7\u00e3o<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7cd0ab6 elementor-widget elementor-widget-heading\" data-id=\"7cd0ab6\" data-element_type=\"widget\" id=\"resumo\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Resumo<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a5cdc elementor-widget elementor-widget-text-editor\" data-id=\"13a5cdc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Ao comprar uma persiana para seu escrit\u00f3rio voc\u00ea deve escolher entre 3 materiais (tecido, alum\u00ednio ou madeira), depois sobre 6 modelos principais (rol\u00f4, romana, painel, double vision, vertical e horizontal) e na sequ\u00eancia pelo estilo (Screen 1%, Screen 3%, Screen 5%, Blackout, Transl\u00facido, Alum\u00ednio ou Madeira) e por fim se deseja acionamento manual ou automatizado para sua persiana.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac6d538 elementor-widget elementor-widget-text-editor\" data-id=\"ac6d538\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Comprar uma <strong>persiana para escrit\u00f3rio <\/strong>n\u00e3o \u00e9 tarefa f\u00e1cil. Se quiser ajuda, agende uma visita t\u00e9cnica com a gente, n\u00f3s apresentaremos nosso mostru\u00e1rio, lhe daremos sugest\u00f5es e faremos as medi\u00e7\u00f5es do seu ambiente.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-abcab02 elementor-widget elementor-widget-text-editor\" data-id=\"abcab02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Seguindo essas etapas, voc\u00ea pode comprar a persiana certa para o seu escrit\u00f3rio e desfrutar de um ambiente mais confort\u00e1vel, que com certeza aumentar\u00e1 sua produtividade.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-537f10a elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"537f10a\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">Agendar visita t\u00e9cnica<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-43a46e4 elementor-widget elementor-widget-text-editor\" data-id=\"43a46e4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Atendimento em toda Regi\u00e3o Metropolitana de S\u00e3o Paulo e Litoral Paulista (S\u00e3o Paulo, Barueri, Cotia, Jundia\u00ed, Mau\u00e1, Santana do Parna\u00edba, Santos, S\u00e3o Bernardo, S\u00e3o Caetano, &#8230;)\u00a0<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c0a7fc9 elementor-section-boxed elementor-section-height-default elementor-section-height-default elementor-invisible\" data-id=\"c0a7fc9\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;,&quot;animation_mobile&quot;:&quot;fadeIn&quot;,&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ad1fc84\" data-id=\"ad1fc84\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-058f267 elementor-widget elementor-widget-heading\" data-id=\"058f267\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Como Trabalhamos<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-72e29f9 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"72e29f9\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<link rel=\"stylesheet\" href=\"https:\/\/joiadecoracoes.com.br\/wp-content\/plugins\/elementor\/assets\/css\/widget-icon-list.min.css\">\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">1- COMENTE SUA IDEIA ENTRANDO EM CONTATO PELO WHATSAPP<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">2- RECEBA UM OR\u00c7AMENTO PR\u00c9VIO<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">3- AGENDE UMA VISITA T\u00c9CNICA PARA DISCUSS\u00c3O DE MODELOS E MEDI\u00c7\u00c3O OFICIAL<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">4- RECEBA SEU OR\u00c7AMENTO FINAL<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"far fa-gem\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">5- AGENDE A INSTALA\u00c7\u00c3O E DEPOIS \u00c9 S\u00d3 CURTIR SEU NOVO AMBIENTE<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3118107 elementor-widget elementor-widget-spacer\" data-id=\"3118107\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-025c788 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"025c788\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"http:\/\/wa.me\/5511963441314\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">comente sua ideia<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc22fdf elementor-widget elementor-widget-spacer\" data-id=\"cc22fdf\" data-element_type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f7bc9a1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f7bc9a1\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8a36c0b\" data-id=\"8a36c0b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74e30a1 elementor-widget elementor-widget-image\" data-id=\"74e30a1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"461\" src=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-768x461.png\" class=\"attachment-medium_large size-medium_large wp-image-85\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-768x461.png 768w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-300x180.png 300w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-1024x614.png 1024w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-1536x922.png 1536w, https:\/\/joiadecoracoes.com.br\/wp-content\/uploads\/2023\/03\/customcolor_logo_transparent_background-2048x1229.png 2048w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-071f480 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"071f480\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a825cc\" data-id=\"6a825cc\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cac5f74 elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"cac5f74\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">REDES SOCIAIS<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1930637 elementor-widget-divider--view-line elementor-invisible elementor-widget elementor-widget-divider\" data-id=\"1930637\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInLeft&quot;}\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c4d28c2 elementor-invisible elementor-widget elementor-widget-text-editor\" data-id=\"c4d28c2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>ACOMPANHE NOSSO TRABALHO NO INSTAGRAM<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdac1e2 elementor-mobile-align-center elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"cdac1e2\" data-element_type=\"widget\" data-settings=\"{&quot;_animation_mobile&quot;:&quot;fadeInUp&quot;,&quot;_animation&quot;:&quot;fadeInUp&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t<a href=\"https:\/\/www.instagram.com\/joia_decoracoes\" class=\"elementor-button-link elementor-button elementor-size-lg elementor-animation-shrink\" role=\"button\" id=\"btn_instagram\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-text\">INSTAGRAM<\/span>\n\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Persiana Para Escrit\u00f3rio Anterior Pr\u00f3ximo A partir de R$ 149,97 o m\u00b2 OR\u00c7AMENTO E se voc\u00ea comprar uma persiana que n\u00e3o combina com seu escrit\u00f3rio? E se ela n\u00e3o bloquear a luz como voc\u00ea gostaria? Comprar uma persiana para escrit\u00f3rio\u00a0exige conhecer as diferentes op\u00e7\u00f5es de material, modelo e estilos de persianas. Separamos algumas dicas para [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"_joinchat":[]},"_links":{"self":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/578"}],"collection":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=578"}],"version-history":[{"count":73,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/578\/revisions"}],"predecessor-version":[{"id":1914,"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/pages\/578\/revisions\/1914"}],"wp:attachment":[{"href":"https:\/\/joiadecoracoes.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}